{"id":5118,"date":"2021-11-15T14:36:32","date_gmt":"2021-11-15T14:36:32","guid":{"rendered":"https:\/\/scalp-sas.com\/?post_type=video&#038;p=5118"},"modified":"2023-08-11T11:53:56","modified_gmt":"2023-08-11T11:53:56","slug":"nettoyer-rapidement-facade","status":"publish","type":"video","link":"https:\/\/scalp-sas.com\/en\/video\/quick-facade-cleaning\/","title":{"rendered":"Quickly clean your facade - SCALP RENOV'EXPRESS"},"content":{"rendered":"<p>SCALP RENOV'EXPRESS makes it possible to quickly remove black marks caused by atmospheric pollution from your facade. It's a multi-purpose cleaner that brings your surfaces back to life in record time. This cleaner is designed to provide a fast, effective solution. SCALP RENOV'EXPRESS can be applied to roofs, facades, floors and exterior walls. It instantly removes soiling caused by atmospheric pollution that has dulled their appearance.<\/p>\n\n\n\n<p>Your surfaces can fall victim to the ravages of time and the elements. SCALP R\u00c9NOV'EXPRESS acts as a renovation agent. It restores the original appearance of your surfaces and gives your home a whole new look. Whether your surfaces are made of organic, mineral, hydraulic or lime-based materials, this cleaner cleans them effectively, erasing the signs of time and wear.<\/p>\n\n\n\n<p>The major advantage of SCALP R\u00c9NOV'EXPRESS is its ease of use. No rinsing is required, saving you time and energy. Simply apply the cleaner, and its powerful cleansing agents remove stubborn dirt and impurities accumulated over time.<\/p>\n\n\n\n<p>Whether you're looking for a rejuvenating treatment for your roof, a brilliant restoration for your facades or a quick renovation for your floors and walls, SCALP R\u00c9NOV'EXPRESS promises a fast, effective solution. Transform your spaces with this all-in-one cleaner and rediscover the original beauty of your surfaces without the hassle of rinsing.<\/p>","protected":false},"excerpt":{"rendered":"<p>Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c&rsquo;est possible avec SCALP RENOV&rsquo;EXPRESS. C&rsquo;est un nettoyant polyvalent qui redonne vie \u00e0 vos surfaces en un temps records. Ce nettoyant est con\u00e7u pour offrir une solution rapide et efficace. SCALP RENOV&rsquo;EXPRESS s&rsquo;applique sur toitures, fa\u00e7ades, sols et murs ext\u00e9rieurs. Il \u00e9limine en [&hellip;]<\/p>","protected":false},"author":2,"featured_media":5119,"parent":0,"menu_order":0,"comment_status":"open","ping_status":"open","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categorie_video":[34],"class_list":["post-5118","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categorie_video-batiment"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nettoyer rapidement sa fa\u00e7ade - SCALP RENOV&#039;EXPRESS<\/title>\n<meta name=\"description\" content=\"Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c&#039;est possible avec SCALP RENOV&#039;EXPRESS.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scalp-sas.com\/en\/video\/quick-facade-cleaning\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nettoyer rapidement sa fa\u00e7ade - SCALP RENOV&#039;EXPRESS\" \/>\n<meta property=\"og:description\" content=\"Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c&#039;est possible avec SCALP RENOV&#039;EXPRESS.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scalp-sas.com\/en\/video\/quick-facade-cleaning\/\" \/>\n<meta property=\"og:site_name\" content=\"SCALP SAS\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T11:53:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41-1024x573.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"573\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/\",\"name\":\"Nettoyer rapidement sa fa\u00e7ade - SCALP RENOV'EXPRESS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41.png\",\"datePublished\":\"2021-11-15T14:36:32+00:00\",\"dateModified\":\"2023-08-11T11:53:56+00:00\",\"description\":\"Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c'est possible avec SCALP RENOV'EXPRESS.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/#primaryimage\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41.png\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41.png\",\"width\":1906,\"height\":1067,\"caption\":\"Super nettoyant et d\u00e9sincrustant fa\u00e7ade\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/nettoyer-rapidement-facade\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"videos\",\"item\":\"https:\\\/\\\/scalp-sas.com\\\/es\\\/videos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nettoyer rapidement sa fa\u00e7ade &#8211; SCALP RENOV&rsquo;EXPRESS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"name\":\"SCALP SAS\",\"description\":\"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scalp-sas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\",\"name\":\"SCALP SAS\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"width\":526.433,\"height\":274.69,\"caption\":\"SCALP SAS\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/scalp-sas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalp_sas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nettoyer rapidement sa fa\u00e7ade - SCALP RENOV'EXPRESS","description":"Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c'est possible avec SCALP RENOV'EXPRESS.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scalp-sas.com\/en\/video\/quick-facade-cleaning\/","og_locale":"en_US","og_type":"article","og_title":"Nettoyer rapidement sa fa\u00e7ade - SCALP RENOV'EXPRESS","og_description":"Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c'est possible avec SCALP RENOV'EXPRESS.","og_url":"https:\/\/scalp-sas.com\/en\/video\/quick-facade-cleaning\/","og_site_name":"SCALP SAS","article_modified_time":"2023-08-11T11:53:56+00:00","og_image":[{"width":1024,"height":573,"url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41-1024x573.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/","url":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/","name":"Nettoyer rapidement sa fa\u00e7ade - SCALP RENOV'EXPRESS","isPartOf":{"@id":"https:\/\/scalp-sas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/#primaryimage"},"image":{"@id":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/#primaryimage"},"thumbnailUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41.png","datePublished":"2021-11-15T14:36:32+00:00","dateModified":"2023-08-11T11:53:56+00:00","description":"Nettoyer rapidement sa fa\u00e7ade des traces noires caus\u00e9es par la pollution atmosph\u00e9rique, c'est possible avec SCALP RENOV'EXPRESS.","breadcrumb":{"@id":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/#primaryimage","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41.png","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/Capture-de\u0301cran-2021-11-15-a\u0300-15.35.41.png","width":1906,"height":1067,"caption":"Super nettoyant et d\u00e9sincrustant fa\u00e7ade"},{"@type":"BreadcrumbList","@id":"https:\/\/scalp-sas.com\/video\/nettoyer-rapidement-facade\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"videos","item":"https:\/\/scalp-sas.com\/es\/videos\/"},{"@type":"ListItem","position":2,"name":"Nettoyer rapidement sa fa\u00e7ade &#8211; SCALP RENOV&rsquo;EXPRESS"}]},{"@type":"WebSite","@id":"https:\/\/scalp-sas.com\/#website","url":"https:\/\/scalp-sas.com\/","name":"SCALP SAS","description":"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans","publisher":{"@id":"https:\/\/scalp-sas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scalp-sas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/scalp-sas.com\/#organization","name":"SCALP SAS","url":"https:\/\/scalp-sas.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","width":526.433,"height":274.69,"caption":"SCALP SAS"},"image":{"@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/scalp-sas\/","https:\/\/www.instagram.com\/scalp_sas\/"]}]}},"_links":{"self":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/video\/5118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/comments?post=5118"}],"version-history":[{"count":5,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/video\/5118\/revisions"}],"predecessor-version":[{"id":9667,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/video\/5118\/revisions\/9667"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/media\/5119"}],"wp:attachment":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/media?parent=5118"}],"wp:term":[{"taxonomy":"categorie_video","embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/categorie_video?post=5118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}