{"id":24,"count":9,"description":"<h2 class=\"p1\"><b>Qu\u2019est-ce qu\u2019un produit d\u00e9capant ?<\/b><\/h2>\r\n<p class=\"p2\">Un d\u00e9capant est un produit chimique formul\u00e9, d\u00e9velopp\u00e9 et fabriqu\u00e9 pour r\u00e9nover les surfaces en les d\u00e9barrassant des rev\u00eatements existants. Il \u00e9limine les couches de peinture, de vernis, de laque, de rouille sur divers mat\u00e9riaux comme le bois, le m\u00e9tal ou encore le b\u00e9ton. Notre gamme professionnelle de d\u00e9capants s\u2019utilise sur de nombreux supports tels que les fa\u00e7ades, escaliers, fen\u00eatres, meubles, etc. En effet, les d\u00e9capants s\u2019emploient dans divers projets de r\u00e9novation et restauration pour remettre \u00e0 neuf les surfaces avant d\u2019appliquer un nouveau rev\u00eatement ou simplement retrouver leur aspect d\u2019origine. Ils peuvent \u00eatre sous forme de gel, liquide ou encore en a\u00e9rosol.<\/p>\r\n\r\n<h3 class=\"p2\"><b>Quel produit pour d\u00e9caper une peinture ?<\/b><\/h3>\r\n<p class=\"p2\">Par manque d\u2019entretien, \u00e0 cause du temps ou tout simplement envie de changement, la peinture peut demander \u00e0 \u00eatre r\u00e9appliqu\u00e9e. Il est donc recommand\u00e9 de d\u00e9caper l\u2019ancienne couche de peinture pour avoir un r\u00e9sultat optimal. Pour cela, il existe plusieurs types de d\u00e9capants fa\u00e7ade ou universel en gel ou liquide. Le choix se fera en fonction de votre support. Par exemple, les d\u00e9capants gels sont parfait pour \u00eatre remettre \u00e0 neuf des supports verticaux. Gr\u00e2ce \u00e0 leur formule g\u00e9lifi\u00e9e, ils ne coulent pas.<\/p>\r\n\r\n<h3 class=\"p2\"><b>Quel produit pour d\u00e9caper du bois ?\u00a0<\/b><\/h3>\r\n<p class=\"p2\">Vous souhaitez remettre \u00e0 neuf vos volets ou encore r\u00e9nover un vieux meuble ? Nos d\u00e9capants universels sont parfaitement adapt\u00e9s pour d\u00e9caper des supports en bois. En gel ou liquide, nos d\u00e9capants \u00e9liminent parfaitement les rev\u00eatements (vernis, peinture, cire ou encore lasure) tout en pr\u00e9servant le support en bois.<\/p>\r\n<p class=\"p2\">Nos d\u00e9capants professionnels ne n\u00e9cessitent pas de rin\u00e7age. Vous pouvez donc appliquer un nouveau rev\u00eatement sur votre support (porte, escalier, fen\u00eatre, terrasse, etc.). De plus, si vous souhaitez d\u00e9griser et redonner une couleur naturelle \u00e0 votre bois, nous vous recommandons notre d\u00e9griseur pour bois, <a href=\"https:\/\/scalp-sas.com\/nos-produits\/degriseur-bois-neutral-da-66\/\">NEUTRAL DA 66<\/a>.<\/p>\r\n\r\n<h3 class=\"p1\"><b>Quel produit pour d\u00e9caper du m\u00e9tal ?<\/b><\/h3>\r\n<p class=\"p2\">Avec le temps, les rev\u00eatements des supports en m\u00e9tal comme les portails ou encore les tables de jardin s\u2019abiment. Nous vous recommandons donc d\u2019utiliser un de nos d\u00e9capants universels : <a href=\"https:\/\/scalp-sas.com\/nos-produits\/decapant-peinture-gel-scalpex-nw\/\">SCALPEX NW<\/a>,\u00a0<a href=\"https:\/\/scalp-sas.com\/nos-produits\/decapant-peinture-liquide-scalpik-decap-sec-nw\/\">SCALPIK DECAP\u2019SEC NW<\/a>\u00a0ou\u00a0<a href=\"https:\/\/scalp-sas.com\/nos-produits\/decapant-peinture-aerosol-scalpex-ae-nw\/\">SCALPEX AE NW.<\/a> Ces trois d\u00e9capants \u00e9liminent parfaitement les peintures, vernis, colles ou encore mastics. Une fois remis \u00e0 neuf, vous pouvez alors appliquer un nouveau rev\u00eatement ou laisser le support en m\u00e9tal tel quel si vous le souhaitez.<\/p>\r\n<p class=\"p2\">Si vous choisissez de repeindre le support, il est conseill\u00e9 d\u2019appliquer une <a href=\"https:\/\/scalp-sas.com\/nos-produits\/degraissant-derochant-surfaces-metalliques-derox-320\/\">base d\u2019accrochage.<\/a> Cela permet d\u2019\u00e9liminer les scories et d\u2019\u00e9viter tout risque de d\u00e9collement, de claquage ou d\u2019\u00e9caillage de la peinture.<\/p>\r\n\r\n<h3 class=\"p1\"><b>Quel produit pour d\u00e9caper une fa\u00e7ade ?\u00a0<\/b><\/h3>\r\n<p class=\"p2\">Avant de proc\u00e9der au\u00a0<a href=\"https:\/\/scalp-sas.com\/decaper\/les-travaux-de-decapage\/\">d\u00e9capage d\u2019une fa\u00e7ade<\/a>, il est primordial de d\u00e9terminer la nature du rev\u00eatement (cr\u00e9pi, pl\u00e2tre, b\u00e9ton, pierre, brique, bois, p\u00e2te de verre, etc.). Nos diff\u00e9rents d\u00e9capants (SCALPEX SD, SCALPEX SD+, SCALPEX AQUA 50) \u00e9liminent efficacement les anciennes peintures du b\u00e2timent, les films minces, les syst\u00e8mes d\u2019imperm\u00e9abilisation de fa\u00e7ade, les rev\u00eatements plastiques \u00e9pais (RPE), les rev\u00eatements semi-\u00e9pais (RSE), etc.\u00a0 On utilise ces produits g\u00e9n\u00e9ralement lors de travaux de ravalement de fa\u00e7ade.<\/p>\r\n\r\n<h3 class=\"p2\"><b>Quel produit pour d\u00e9caper du carrelage ?\u00a0<\/b><\/h3>\r\n<p class=\"p2\">Lors de la pose d\u2019un carrelage, il est courant d\u2019avoir des voiles de ciment. Pour enlever les laitances, il est recommand\u00e9 d\u2019appliquer un produit adapt\u00e9 non agressif pour le carrelage. Pour cela, <a href=\"https:\/\/scalp-sas.com\/nos-produits\/nettoyant-laitance-voile-ciment-scalp-solnet\/\">SCALP SOL\u2019NET<\/a> est id\u00e9al pour d\u00e9caper et nettoyer toutes les salet\u00e9s de fin de chantier. En effet, sans solvant, il \u00e9limine les voiles et laitance de ciment, r\u00e9sidus de pl\u00e2tre, remont\u00e9es calcaires, rouilles, etc.<\/p>\r\n\r\n<h2 class=\"p2\"><b>Tout savoir sur l\u2019application d\u2019un d\u00e9capant :<\/b><\/h2>\r\n<p class=\"p2\">Pour r\u00e9ussir le d\u00e9capage d\u2019un rev\u00eatement sur n\u2019importe quel support, respecter le temps d\u2019action du produit est un \u00e9l\u00e9ment clef ! Chaque produit poss\u00e8de ses sp\u00e9cificit\u00e9s, il est donc essentiel de consulter la fiche technique du produit ou de consulter un commercial avant de commencer.<\/p>\r\n\r\n\r\n<hr \/>\r\n<p class=\"p2\"><em>Retrouvez nos produits en action<\/em>\u00a0:<\/p>\r\n\r\n<ul class=\"ul1\">\r\n \t<li class=\"li2\"><span class=\"s1\"><a href=\"https:\/\/scalp-sas.com\/video\/decapant-facade-ultra-rapide-scalpex-sd\/\"><span class=\"s2\">https:\/\/scalp-sas.com\/video\/decapant-facade-ultra-rapide-scalpex-sd\/<\/span><\/a><\/span><\/li>\r\n \t<li class=\"li2\"><span class=\"s1\"><a href=\"https:\/\/scalp-sas.com\/video\/decapant-liquide-surpsuissant-sans-rincage-scalpik-decap-sec-nw\/\"><span class=\"s2\">https:\/\/scalp-sas.com\/video\/decapant-liquide-surpsuissant-sans-rincage-scalpik-decap-sec-nw\/<\/span><\/a><\/span><\/li>\r\n \t<li class=\"li2\"><span class=\"s1\"><a href=\"https:\/\/scalp-sas.com\/video\/super-decapant-gelifie-nouvelle-generation-scalpex-nw\/\"><span class=\"s2\">https:\/\/scalp-sas.com\/video\/super-decapant-gelifie-nouvelle-generation-scalpex-nw\/<\/span><\/a><\/span><\/li>\r\n \t<li class=\"li2\"><span class=\"s1\"><a href=\"https:\/\/scalp-sas.com\/video\/decapant-universel-aerosol-scalpex-ae-nw\/\"><span class=\"s2\">https:\/\/scalp-sas.com\/video\/decapant-universel-aerosol-scalpex-ae-nw\/<\/span><\/a><\/span><\/li>\r\n<\/ul>\r\n<p class=\"p2\"><em>Retrouvez tous nos conseils<\/em> :<\/p>\r\n\r\n<ul>\r\n \t<li class=\"p2\"><a href=\"https:\/\/scalp-sas.com\/decaper\/les-travaux-de-decapage\/\">https:\/\/scalp-sas.com\/decaper\/les-travaux-de-decapage\/<\/a><\/li>\r\n \t<li class=\"p2\"><a href=\"https:\/\/scalp-sas.com\/decaper\/quand-faire-ravalement-facade\/\">https:\/\/scalp-sas.com\/decaper\/quand-faire-ravalement-facade\/<\/a><\/li>\r\n \t<li class=\"p2\"><a href=\"https:\/\/scalp-sas.com\/actualites\/protection-et-entretien-des-batiments\/\">https:\/\/scalp-sas.com\/actualites\/protection-et-entretien-des-batiments\/<\/a><\/li>\r\n<\/ul>","link":"https:\/\/scalp-sas.com\/en\/product-category\/our-product\/construction\/strippers\/","name":"D\u00e9capants","slug":"decapants","taxonomy":"product_cat","parent":23,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00e9capants - SCALP SAS<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez les produits de la gamme b\u00e2timent d\u00e9di\u00e9s aux d\u00e9capants. Retrouvez des d\u00e9capants fa\u00e7ades, universel g\u00e9lifi\u00e9 et liquide, en a\u00e9rosol, etc.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scalp-sas.com\/en\/product-category\/batiment\/decapants\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00e9capants - SCALP SAS\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez les produits de la gamme b\u00e2timent d\u00e9di\u00e9s aux d\u00e9capants. Retrouvez des d\u00e9capants fa\u00e7ades, universel g\u00e9lifi\u00e9 et liquide, en a\u00e9rosol, etc.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scalp-sas.com\/en\/product-category\/batiment\/decapants\/\" \/>\n<meta property=\"og:site_name\" content=\"SCALP SAS\" \/>\n<meta property=\"og:image\" content=\"https:\/\/scalp-sas.com\/wp-content\/uploads\/2022\/01\/logo-scalp-site.png\" \/>\n\t<meta property=\"og:image:width\" content=\"350\" \/>\n\t<meta property=\"og:image:height\" content=\"100\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/categorie-produit\\\/nos-produits\\\/batiment\\\/decapants\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/categorie-produit\\\/batiment\\\/decapants\\\/\",\"name\":\"D\u00e9capants - SCALP SAS\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\"},\"description\":\"D\u00e9couvrez les produits de la gamme b\u00e2timent d\u00e9di\u00e9s aux d\u00e9capants. Retrouvez des d\u00e9capants fa\u00e7ades, universel g\u00e9lifi\u00e9 et liquide, en a\u00e9rosol, etc.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/categorie-produit\\\/batiment\\\/decapants\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/categorie-produit\\\/batiment\\\/decapants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Nos produits\",\"item\":\"https:\\\/\\\/scalp-sas.com\\\/es\\\/nuestros-productos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nos produits\",\"item\":\"https:\\\/\\\/scalp-sas.com\\\/categorie-produit\\\/nos-produits\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"B\u00e2timent\",\"item\":\"https:\\\/\\\/scalp-sas.com\\\/categorie-produit\\\/nos-produits\\\/batiment\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"D\u00e9capants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"name\":\"SCALP SAS\",\"description\":\"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scalp-sas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\",\"name\":\"SCALP SAS\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"width\":526.433,\"height\":274.69,\"caption\":\"SCALP SAS\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/scalp-sas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalp_sas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00e9capants - SCALP SAS","description":"D\u00e9couvrez les produits de la gamme b\u00e2timent d\u00e9di\u00e9s aux d\u00e9capants. Retrouvez des d\u00e9capants fa\u00e7ades, universel g\u00e9lifi\u00e9 et liquide, en a\u00e9rosol, etc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scalp-sas.com\/en\/product-category\/batiment\/decapants\/","og_locale":"en_US","og_type":"article","og_title":"D\u00e9capants - SCALP SAS","og_description":"D\u00e9couvrez les produits de la gamme b\u00e2timent d\u00e9di\u00e9s aux d\u00e9capants. Retrouvez des d\u00e9capants fa\u00e7ades, universel g\u00e9lifi\u00e9 et liquide, en a\u00e9rosol, etc.","og_url":"https:\/\/scalp-sas.com\/en\/product-category\/batiment\/decapants\/","og_site_name":"SCALP SAS","og_image":[{"width":350,"height":100,"url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2022\/01\/logo-scalp-site.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/scalp-sas.com\/categorie-produit\/nos-produits\/batiment\/decapants\/","url":"https:\/\/scalp-sas.com\/categorie-produit\/batiment\/decapants\/","name":"D\u00e9capants - SCALP SAS","isPartOf":{"@id":"https:\/\/scalp-sas.com\/#website"},"description":"D\u00e9couvrez les produits de la gamme b\u00e2timent d\u00e9di\u00e9s aux d\u00e9capants. Retrouvez des d\u00e9capants fa\u00e7ades, universel g\u00e9lifi\u00e9 et liquide, en a\u00e9rosol, etc.","breadcrumb":{"@id":"https:\/\/scalp-sas.com\/categorie-produit\/batiment\/decapants\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/scalp-sas.com\/categorie-produit\/batiment\/decapants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Nos produits","item":"https:\/\/scalp-sas.com\/es\/nuestros-productos\/"},{"@type":"ListItem","position":2,"name":"Nos produits","item":"https:\/\/scalp-sas.com\/categorie-produit\/nos-produits\/"},{"@type":"ListItem","position":3,"name":"B\u00e2timent","item":"https:\/\/scalp-sas.com\/categorie-produit\/nos-produits\/batiment\/"},{"@type":"ListItem","position":4,"name":"D\u00e9capants"}]},{"@type":"WebSite","@id":"https:\/\/scalp-sas.com\/#website","url":"https:\/\/scalp-sas.com\/","name":"SCALP SAS","description":"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans","publisher":{"@id":"https:\/\/scalp-sas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scalp-sas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/scalp-sas.com\/#organization","name":"SCALP SAS","url":"https:\/\/scalp-sas.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","width":526.433,"height":274.69,"caption":"SCALP SAS"},"image":{"@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/scalp-sas\/","https:\/\/www.instagram.com\/scalp_sas\/"]}]}},"_links":{"self":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/product_cat\/24","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/product_cat\/23"}],"wp:post_type":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/product?product_cat=24"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}