{"id":115531,"date":"2025-07-15T08:06:22","date_gmt":"2025-07-15T08:06:22","guid":{"rendered":"https:\/\/scalp-sas.com\/?p=115531"},"modified":"2025-08-11T09:21:04","modified_gmt":"2025-08-11T09:21:04","slug":"scalp-sas-medaille-bronze-ecovadis","status":"publish","type":"post","link":"https:\/\/scalp-sas.com\/en\/news\/scalp-sas-medaille-bronze-ecovadis\/","title":{"rendered":"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis : une reconnaissance strat\u00e9gique de notre engagement RSE"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"115531\" class=\"elementor elementor-115531\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05c8475 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05c8475\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99072a9\" data-id=\"99072a9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-47cd0b1 elementor-widget elementor-widget-text-editor\" data-id=\"47cd0b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Chez <\/span><b>SCALP SAS<\/b><span style=\"font-weight: 400;\">, entreprise fran\u00e7aise innovante sp\u00e9cialis\u00e9e dans le d\u00e9veloppement de solutions techniques pour le <\/span><b>nettoyage<\/b><span style=\"font-weight: 400;\">, le <\/span><b>d\u00e9capage<\/b><span style=\"font-weight: 400;\"> et la <\/span><b>protection des mat\u00e9riaux du b\u00e2timent<\/b><span style=\"font-weight: 400;\">,<\/span><b> transports et industrie<\/b><span style=\"font-weight: 400;\">, nous sommes fiers d\u2019annoncer l\u2019obtention de la <\/span><b>m\u00e9daille de bronze EcoVadis<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><p><span style=\"font-weight: 400;\">Ce label de r\u00e9f\u00e9rence vient <\/span><b>r\u00e9compenser nos engagements concrets en mati\u00e8re de responsabilit\u00e9 soci\u00e9tale et environnementale<\/b><span style=\"font-weight: 400;\">, et marque une \u00e9tape significative dans notre strat\u00e9gie de d\u00e9veloppement durable. Au-del\u00e0 de la distinction, c\u2019est <\/span><b>un signal fort adress\u00e9 \u00e0 l\u2019ensemble de notre \u00e9cosyst\u00e8me<\/b><span style=\"font-weight: 400;\"> : clients, partenaires, fournisseurs, collaborateurs, institutions.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68ba2d1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68ba2d1\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-fb21e61\" data-id=\"fb21e61\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-02c5fb8 elementor-widget elementor-widget-heading\" data-id=\"02c5fb8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><a href=\"https:\/\/ecovadis.com\/\">EcoVadis : un r\u00e9f\u00e9rentiel international exigeant<\/a><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7d6f86a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7d6f86a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-784bef1\" data-id=\"784bef1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b835088 elementor-widget elementor-widget-text-editor\" data-id=\"b835088\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><b>EcoVadis<\/b><span style=\"font-weight: 400;\"> est aujourd\u2019hui la plateforme d\u2019\u00e9valuation RSE la plus reconnue \u00e0 l\u2019\u00e9chelle mondiale, avec plus de 100 000 entreprises \u00e9valu\u00e9es dans plus de 175 pays. Elle s\u2019impose comme un <\/span><b>standard incontournable<\/b><span style=\"font-weight: 400;\">, notamment dans les secteurs du BTP, de l\u2019industrie, de la chimie, de la distribution et des march\u00e9s publics.<\/span><\/p><p><span style=\"font-weight: 400;\">L\u2019\u00e9valuation se fonde sur 21 crit\u00e8res regroup\u00e9s en <\/span><b>4 grands piliers<\/b><span style=\"font-weight: 400;\"> :<\/span><\/p><ul><li aria-level=\"1\"><h3><b>Environnement :\u00a0<\/b><\/h3><\/li><\/ul><p><span style=\"font-weight: 400;\">Concepteur de solutions techniques, SCALP SAS int\u00e8gre les enjeux environnementaux d\u00e8s la phase de R&amp;D. Notre objectif : <\/span><b>r\u00e9duire l\u2019impact des produits sur l\u2019homme et la plan\u00e8te<\/b><span style=\"font-weight: 400;\">, sans compromis sur l\u2019efficacit\u00e9.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">D\u00e9veloppement de <\/span><b>formules \u00e0 faible impact environnemental<\/b><span style=\"font-weight: 400;\">, alternatives aux produits toxiques ou polluants.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Optimisation des proc\u00e9d\u00e9s industriels pour <\/span><b>limiter les rejets<\/b><span style=\"font-weight: 400;\"> et r\u00e9duire la consommation d\u2019eau et d\u2019\u00e9nergie.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mise en \u0153uvre d\u2019un <\/span><b>tri rigoureux des d\u00e9chets<\/b><span style=\"font-weight: 400;\"> et de fili\u00e8res de valorisation adapt\u00e9es.<\/span><\/li><\/ul><p><br \/><b><\/b><\/p><ul><li aria-level=\"1\"><h3><b>Social &amp; Droits humains :<\/b><\/h3><\/li><\/ul><p><span style=\"font-weight: 400;\">Dans notre secteur, o\u00f9 la <\/span><b>s\u00e9curit\u00e9 et les conditions de travail<\/b><span style=\"font-weight: 400;\"> sont essentielles, SCALP SAS veille \u00e0 offrir un environnement sain, stable et valorisant \u00e0 ses collaborateurs :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Une politique RH fond\u00e9e sur le <\/span><b>respect de l\u2019\u00e9galit\u00e9 des chances<\/b><span style=\"font-weight: 400;\"> et l\u2019<\/span><b>inclusion<\/b><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Des actions concr\u00e8tes pour garantir la <\/span><b>s\u00e9curit\u00e9 des \u00e9quipes<\/b><span style=\"font-weight: 400;\">, sur site et en laboratoire.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Des parcours de <\/span><b>formation technique continue<\/b><span style=\"font-weight: 400;\"> pour renforcer les comp\u00e9tences m\u00e9tiers, en lien avec les \u00e9volutions r\u00e9glementaires et technologiques.<\/span><\/li><\/ul><p><br \/><b><\/b><\/p><ul><li aria-level=\"1\"><h3><b>\u00c9thique :<\/b><\/h3><\/li><\/ul><p><span style=\"font-weight: 400;\">The <\/span><b>conformit\u00e9 r\u00e9glementaire<\/b><span style=\"font-weight: 400;\"> est une exigence quotidienne dans notre activit\u00e9. SCALP SAS y ajoute un engagement plus large en faveur de l\u2019\u00e9thique :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mise en place d\u2019une <\/span><b>politique anti-corruption<\/b><span style=\"font-weight: 400;\"> et d\u2019un <\/span><b>dispositif de signalement interne<\/b><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Respect strict des normes en vigueur, notamment dans la fabrication, le stockage et la distribution de nos produits.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Culture d\u2019entreprise fond\u00e9e sur l\u2019<\/span><b>exemplarit\u00e9<\/b><span style=\"font-weight: 400;\">, la <\/span><b>clart\u00e9 des engagements<\/b><span style=\"font-weight: 400;\"> and the <\/span><b>respect mutuel<\/b><span style=\"font-weight: 400;\">.<\/span><\/li><\/ul><p><br \/><b><\/b><\/p><ul><li aria-level=\"1\"><h3><b>Achats responsables :<\/b><\/h3><\/li><\/ul><p><span style=\"font-weight: 400;\">SCALP SAS veille \u00e0 ce que sa politique d\u2019achats refl\u00e8te ses engagements RSE :<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>S\u00e9lection de fournisseurs responsables<\/b><span style=\"font-weight: 400;\">, notamment pour les mati\u00e8res premi\u00e8res chimiques et les emballages.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Collaboration privil\u00e9gi\u00e9e avec des partenaires <\/span><b>locaux<\/b><span style=\"font-weight: 400;\"> and <\/span><b>certifi\u00e9s<\/b><span style=\"font-weight: 400;\">, afin de renforcer l\u2019impact positif sur le tissu \u00e9conomique.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Int\u00e9gration de crit\u00e8res RSE dans les appels d\u2019offres et les processus de r\u00e9f\u00e9rencement.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4401d75 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4401d75\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-77de06b\" data-id=\"77de06b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d255f9 elementor-widget elementor-widget-heading\" data-id=\"9d255f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une reconnaissance fond\u00e9e sur des preuves concr\u00e8tes :\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0c47a43 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0c47a43\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-66 elementor-top-column elementor-element elementor-element-745514b\" data-id=\"745514b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4743bd elementor-widget elementor-widget-text-editor\" data-id=\"f4743bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">L\u2019attribution de la m\u00e9daille de bronze \u00e0 SCALP SAS repose sur une <\/span><b>analyse approfondie de documents officiels<\/b><span style=\"font-weight: 400;\"> : politiques internes, indicateurs chiffr\u00e9s, plans d\u2019actions, audits, engagements sign\u00e9s.<\/span><\/p><p><span style=\"font-weight: 400;\">Nos pratiques ont \u00e9t\u00e9 <\/span><b>compar\u00e9es aux meilleures normes du march\u00e9<\/b><span style=\"font-weight: 400;\">, \u00e0 travers une m\u00e9thodologie stricte et standardis\u00e9e. R\u00e9sultat : <\/span><b>SCALP SAS se classe dans le top 35 % des entreprises les mieux not\u00e9es \u00e0 l\u2019\u00e9chelle mondiale<\/b><span style=\"font-weight: 400;\">, toutes industries confondues.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-a553b11\" data-id=\"a553b11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c96d585 elementor-widget elementor-widget-image\" data-id=\"c96d585\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-2.png\" class=\"attachment-large size-large wp-image-121201\" alt=\"strat\u00e9gie\" srcset=\"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-2.png 1024w, https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-2-300x225.png 300w, https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-2-768x576.png 768w, https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-2-16x12.png 16w, https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-2-600x450.png 600w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f4ea318 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f4ea318\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ed1242c\" data-id=\"ed1242c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a92843a elementor-widget elementor-widget-spacer\" data-id=\"a92843a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-714ca72 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"714ca72\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2134f00\" data-id=\"2134f00\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ad4497d elementor-widget elementor-widget-text-editor\" data-id=\"ad4497d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Un levier de diff\u00e9renciation et de comp\u00e9titivit\u00e9<\/b><\/h3><p><span style=\"font-weight: 400;\">Dans un environnement o\u00f9 la performance \u00e9conomique ne peut plus \u00eatre dissoci\u00e9e de la performance durable, cette distinction constitue un <\/span><b>v\u00e9ritable avantage concurrentiel<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><ul><li aria-level=\"1\"><h4><b>Pour nos clients : des garanties solides<\/b><\/h4><\/li><\/ul><p><span style=\"font-weight: 400;\">La m\u00e9daille EcoVadis nous permet de r\u00e9pondre aux <\/span><b>exigences de plus en plus strictes des donneurs d\u2019ordre<\/b><span style=\"font-weight: 400;\">, notamment dans les appels d\u2019offres publics ou les march\u00e9s \u00e0 dimension environnementale. C\u2019est une preuve objective de notre engagement, qui renforce la <\/span><b>confiance et la transparence<\/b><span style=\"font-weight: 400;\"> dans la relation commerciale.<\/span><\/p><ul><li aria-level=\"1\"><h4><b>Pour nos partenaires et fournisseurs : une cha\u00eene de valeur responsable<\/b><\/h4><\/li><\/ul><p><span style=\"font-weight: 400;\">Nous avons int\u00e9gr\u00e9 des crit\u00e8res RSE dans nos processus d\u2019achats et de s\u00e9lection fournisseurs. Cette m\u00e9daille structure et l\u00e9gitime cette d\u00e9marche, avec une volont\u00e9 claire : <\/span><b>co-construire des relations durables, transparentes et \u00e9thiques<\/b><span style=\"font-weight: 400;\">.<\/span><\/p><ul><li aria-level=\"1\"><h4><b>Pour nos collaborateurs : un environnement de travail engag\u00e9<\/b><\/h4><\/li><\/ul><p><span style=\"font-weight: 400;\">Nos \u00e9quipes sont <\/span><b>au c\u0153ur de notre r\u00e9ussite<\/b><span style=\"font-weight: 400;\">. Cette reconnaissance RSE vient renforcer nos actions internes en mati\u00e8re de bien-\u00eatre au travail, de d\u00e9veloppement des comp\u00e9tences, de s\u00e9curit\u00e9, de diversit\u00e9 et de dialogue social. Nous voulons que chaque collaborateur soit fier de contribuer \u00e0 un projet d\u2019entreprise responsable.<\/span><\/p><ul><li aria-level=\"1\"><h4><b>Pour notre image de marque : un positionnement affirm\u00e9<\/b><\/h4><\/li><\/ul><p><span style=\"font-weight: 400;\">Dans un contexte de <\/span><b>transition \u00e9cologique, soci\u00e9tale et r\u00e9glementaire<\/b><span style=\"font-weight: 400;\">, il ne suffit plus de produire efficacement ; il faut produire <\/span><b>autrement, mieux <\/b><span style=\"font-weight: 400;\">and<\/span><b> durablement<\/b><span style=\"font-weight: 400;\">. Cette m\u00e9daille t\u00e9moigne de notre capacit\u00e9 \u00e0 innover, \u00e0 anticiper et \u00e0 nous aligner sur les grandes transformations en cours.<\/span><\/p><p>\u00a0<\/p><h3><b>Une strat\u00e9gie RSE structur\u00e9e, mesurable et pilot\u00e9e<\/b><\/h3><p><span style=\"font-weight: 400;\">Chez SCALP SAS, la RSE ne se r\u00e9sume pas \u00e0 une charte : c\u2019est une <\/span><b>strat\u00e9gie op\u00e9rationnelle<\/b><span style=\"font-weight: 400;\">, int\u00e9gr\u00e9e \u00e0 tous les niveaux de notre activit\u00e9, de la conception produit \u00e0 la logistique.<\/span><\/p><h4><b>Exemples d\u2019actions concr\u00e8tes :<\/b><\/h4><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>\u00c9co-conception<\/b><span style=\"font-weight: 400;\"> : int\u00e9gration de l\u2019impact environnemental d\u00e8s le d\u00e9veloppement des produits.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>R\u00e9duction des substances \u00e0 risque<\/b><span style=\"font-weight: 400;\"> : d\u00e9marche proactive pour remplacer ou supprimer les composants les plus impactants.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Optimisation \u00e9nerg\u00e9tique<\/b><span style=\"font-weight: 400;\"> de notre site de production \u00e0 Pavillons-Sous-bois.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>D\u00e9veloppement de gammes responsables<\/b><span style=\"font-weight: 400;\"> : produits sans solvant, biod\u00e9gradables, biosourc\u00e9s, \u00e0 faibles \u00e9missions de COV.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Suivi de nos indicateurs RSE<\/b><span style=\"font-weight: 400;\"> via un syst\u00e8me interne de pilotage et d\u2019am\u00e9lioration continue.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Formation et sensibilisation du personnel<\/b><span style=\"font-weight: 400;\"> aux enjeux environnementaux et soci\u00e9taux.<\/span><\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-438eecd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"438eecd\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a4f11c6\" data-id=\"a4f11c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3cfc91b elementor-widget elementor-widget-spacer\" data-id=\"3cfc91b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-035b2b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"035b2b2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8533a02\" data-id=\"8533a02\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-968539b elementor-widget elementor-widget-heading\" data-id=\"968539b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Et maintenant ? Objectif m\u00e9daille d\u2019Or !\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d45c602 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d45c602\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d3848b8\" data-id=\"d3848b8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89ffe67 elementor-widget elementor-widget-text-editor\" data-id=\"89ffe67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">La m\u00e9daille de bronze est un <\/span><b>marqueur de progr\u00e8s<\/b><span style=\"font-weight: 400;\">, mais notre ambition ne s\u2019arr\u00eate pas l\u00e0. Nous avons d\u2019ores et d\u00e9j\u00e0 lanc\u00e9 un <\/span><b>plan d\u2019am\u00e9lioration RSE structur\u00e9<\/b><span style=\"font-weight: 400;\">, avec des objectifs chiffr\u00e9s et des jalons pr\u00e9cis pour les prochains mois.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89347eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"89347eb\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a93e176\" data-id=\"a93e176\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-262d900 elementor-widget elementor-widget-text-editor\" data-id=\"262d900\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h3><b>Objectifs RSE SCALP SAS pour viser la m\u00e9daille d\u2019Or EcoVadis:\u00a0<\/b><\/h3><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><b>R\u00e9duction de 20 % des d\u00e9chets industriels non valoris\u00e9s d\u2019ici 2026<\/b><span style=\"font-weight: 400;\">, via des actions de tri renforc\u00e9, de substitution de mati\u00e8res premi\u00e8res et de meilleure gestion des stocks.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">D\u00e9ploiement d\u2019une <\/span><b>charte \u00e9co-conception<\/b><span style=\"font-weight: 400;\"> pour int\u00e9grer syst\u00e9matiquement les crit\u00e8res environnementaux d\u00e8s la phase R&amp;D.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>R\u00e9duction de 20 % de la consommation \u00e9nerg\u00e9tique<\/b><span style=\"font-weight: 400;\"> sur notre site de production d\u2019ici 3 ans, avec un plan d\u2019actions concret : remplacement d\u2019\u00e9quipements \u00e9nergivores, suivi des consommations, etc.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><b>Objectif z\u00e9ro accident<\/b><span style=\"font-weight: 400;\"> avec plan de formation s\u00e9curit\u00e9 renforc\u00e9 et indicateurs de suivi mensuels.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Int\u00e9gration d\u2019un module RSE dans chaque <\/span><b>plan de formation interne<\/b><span style=\"font-weight: 400;\">, pour sensibiliser tous les collaborateurs \u00e0 ces enjeux.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Formalisation d\u2019une <\/span><b>charte de diversit\u00e9 et d\u2019inclusion<\/b><span style=\"font-weight: 400;\">, avec un objectif de progression sur la parit\u00e9 et l\u2019int\u00e9gration des profils \u00e9loign\u00e9s de l\u2019emploi.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Objectif de <\/span><b>50 % de fournisseurs locaux ou engag\u00e9s dans une d\u00e9marche certifi\u00e9e RSE<\/b><span style=\"font-weight: 400;\"> d\u2019ici 2026.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Ces objectifs structurants marquent une nouvelle \u00e9tape pour SCALP SAS. Notre ambition est claire : faire de la RSE non pas un simple label, mais un <\/span><b>levier de performance durable et partag\u00e9e<\/b><span style=\"font-weight: 400;\">, pour nos clients, nos \u00e9quipes, notre industrie et notre plan\u00e8te.<\/span><\/p><p><span style=\"font-weight: 400;\">Nous remercions nos \u00e9quipes, nos partenaires et nos clients pour leur contribution \u00e0 cette dynamique. Ensemble, nous \u0153uvrons \u00e0 un avenir industriel plus <\/span><b>responsable, s\u00fbr et performant<\/b><span style=\"font-weight: 400;\">.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6eed133 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6eed133\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3b82deb\" data-id=\"3b82deb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b0cf0d elementor-widget elementor-widget-spacer\" data-id=\"8b0cf0d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a48985b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a48985b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8f819cb\" data-id=\"8f819cb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e21d6c elementor-widget elementor-widget-heading\" data-id=\"5e21d6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Vous recherchez un partenaire industriel responsable ?<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0799ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c0799ae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c46705b\" data-id=\"c46705b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d2f3b3 elementor-widget elementor-widget-text-editor\" data-id=\"9d2f3b3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">Vous \u00eates <\/span><b>professionnel du BTP, distributeur, collectivit\u00e9 locale, gestionnaire de patrimoine ou acteur de la r\u00e9novation<\/b><span style=\"font-weight: 400;\"> ? Vous cherchez des solutions techniques <\/span><b>fiables, durables et conformes aux meilleures pratiques RSE<\/b><span style=\"font-weight: 400;\"> ?<\/span><\/p><p><span style=\"font-weight: 400;\">Rejoignez-nous dans cette dynamique de transformation responsable.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00a0<\/span><b>D\u00e9couvrez nos engagements et nos gammes de produits sur<\/b><span style=\"font-weight: 400;\"> :<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\">\ud83d\udd17 <\/span><a href=\"https:\/\/scalp-sas.com\/en\/our-csr-commitments\/\"><span style=\"font-weight: 400;\">https:\/\/scalp-sas.com\/nos-engagements-rse\/<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Chez SCALP SAS, entreprise fran\u00e7aise innovante sp\u00e9cialis\u00e9e dans le d\u00e9veloppement de solutions techniques pour le nettoyage, le d\u00e9capage et la protection des mat\u00e9riaux du b\u00e2timent, transports et industrie, nous sommes fiers d\u2019annoncer l\u2019obtention de la m\u00e9daille de bronze EcoVadis. Ce label de r\u00e9f\u00e9rence vient r\u00e9compenser nos engagements concrets en mati\u00e8re de responsabilit\u00e9 soci\u00e9tale et environnementale, [&hellip;]<\/p>","protected":false},"author":2,"featured_media":121175,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[40],"tags":[],"class_list":["post-115531","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-actualites"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SCALP SAS obtient la m\u00e9daille de bronze EcoVadis<\/title>\n<meta name=\"description\" content=\"SCALP SAS d\u00e9croche la m\u00e9daille de bronze EcoVadis, pla\u00e7ant l\u2019entreprise parmi les 35 % les plus performantes en RSE.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scalp-sas.com\/en\/news\/scalp-sas-medaille-bronze-ecovadis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis\" \/>\n<meta property=\"og:description\" content=\"SCALP SAS d\u00e9croche la m\u00e9daille de bronze EcoVadis, pla\u00e7ant l\u2019entreprise parmi les 35 % les plus performantes en RSE.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scalp-sas.com\/en\/news\/scalp-sas-medaille-bronze-ecovadis\/\" \/>\n<meta property=\"og:site_name\" content=\"SCALP SAS\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-15T08:06:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-11T09:21:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-3-1-e1752564965143.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1917\" \/>\n\t<meta property=\"og:image:height\" content=\"980\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"informatique\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"informatique\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/\"},\"author\":{\"name\":\"informatique\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/person\\\/946f9b44b8f303f48c6e3ab9aa92aebe\"},\"headline\":\"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis : une reconnaissance strat\u00e9gique de notre engagement RSE\",\"datePublished\":\"2025-07-15T08:06:22+00:00\",\"dateModified\":\"2025-08-11T09:21:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/\"},\"wordCount\":511,\"publisher\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Design-sans-titre-3-1-e1752564965143.png\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/\",\"name\":\"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Design-sans-titre-3-1-e1752564965143.png\",\"datePublished\":\"2025-07-15T08:06:22+00:00\",\"dateModified\":\"2025-08-11T09:21:04+00:00\",\"description\":\"SCALP SAS d\u00e9croche la m\u00e9daille de bronze EcoVadis, pla\u00e7ant l\u2019entreprise parmi les 35 % les plus performantes en RSE.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/actualites\\\/scalp-sas-medaille-bronze-ecovadis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Design-sans-titre-3-1-e1752564965143.png\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/Design-sans-titre-3-1-e1752564965143.png\",\"width\":1917,\"height\":980,\"caption\":\"ECOVADIS\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"name\":\"SCALP SAS\",\"description\":\"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scalp-sas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\",\"name\":\"SCALP SAS\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"width\":526.433,\"height\":274.69,\"caption\":\"SCALP SAS\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/scalp-sas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalp_sas\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/person\\\/946f9b44b8f303f48c6e3ab9aa92aebe\",\"name\":\"informatique\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/en\\\/author\\\/marketingscalp-france-fr\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis","description":"SCALP SAS d\u00e9croche la m\u00e9daille de bronze EcoVadis, pla\u00e7ant l\u2019entreprise parmi les 35 % les plus performantes en RSE.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scalp-sas.com\/en\/news\/scalp-sas-medaille-bronze-ecovadis\/","og_locale":"en_US","og_type":"article","og_title":"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis","og_description":"SCALP SAS d\u00e9croche la m\u00e9daille de bronze EcoVadis, pla\u00e7ant l\u2019entreprise parmi les 35 % les plus performantes en RSE.","og_url":"https:\/\/scalp-sas.com\/en\/news\/scalp-sas-medaille-bronze-ecovadis\/","og_site_name":"SCALP SAS","article_published_time":"2025-07-15T08:06:22+00:00","article_modified_time":"2025-08-11T09:21:04+00:00","og_image":[{"width":1917,"height":980,"url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-3-1-e1752564965143.png","type":"image\/png"}],"author":"informatique","twitter_card":"summary_large_image","twitter_misc":{"Written by":"informatique","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/#article","isPartOf":{"@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/"},"author":{"name":"informatique","@id":"https:\/\/scalp-sas.com\/#\/schema\/person\/946f9b44b8f303f48c6e3ab9aa92aebe"},"headline":"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis : une reconnaissance strat\u00e9gique de notre engagement RSE","datePublished":"2025-07-15T08:06:22+00:00","dateModified":"2025-08-11T09:21:04+00:00","mainEntityOfPage":{"@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/"},"wordCount":511,"publisher":{"@id":"https:\/\/scalp-sas.com\/#organization"},"image":{"@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/#primaryimage"},"thumbnailUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-3-1-e1752564965143.png","articleSection":["Actualit\u00e9s"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/","url":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/","name":"SCALP SAS obtient la m\u00e9daille de bronze EcoVadis","isPartOf":{"@id":"https:\/\/scalp-sas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/#primaryimage"},"image":{"@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/#primaryimage"},"thumbnailUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-3-1-e1752564965143.png","datePublished":"2025-07-15T08:06:22+00:00","dateModified":"2025-08-11T09:21:04+00:00","description":"SCALP SAS d\u00e9croche la m\u00e9daille de bronze EcoVadis, pla\u00e7ant l\u2019entreprise parmi les 35 % les plus performantes en RSE.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/scalp-sas.com\/actualites\/scalp-sas-medaille-bronze-ecovadis\/#primaryimage","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-3-1-e1752564965143.png","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2025\/07\/Design-sans-titre-3-1-e1752564965143.png","width":1917,"height":980,"caption":"ECOVADIS"},{"@type":"WebSite","@id":"https:\/\/scalp-sas.com\/#website","url":"https:\/\/scalp-sas.com\/","name":"SCALP SAS","description":"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans","publisher":{"@id":"https:\/\/scalp-sas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scalp-sas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/scalp-sas.com\/#organization","name":"SCALP SAS","url":"https:\/\/scalp-sas.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","width":526.433,"height":274.69,"caption":"SCALP SAS"},"image":{"@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/scalp-sas\/","https:\/\/www.instagram.com\/scalp_sas\/"]},{"@type":"Person","@id":"https:\/\/scalp-sas.com\/#\/schema\/person\/946f9b44b8f303f48c6e3ab9aa92aebe","name":"informatique","url":"https:\/\/scalp-sas.com\/en\/author\/marketingscalp-france-fr\/"}]}},"_links":{"self":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/posts\/115531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/comments?post=115531"}],"version-history":[{"count":4,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/posts\/115531\/revisions"}],"predecessor-version":[{"id":151905,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/posts\/115531\/revisions\/151905"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/media\/121175"}],"wp:attachment":[{"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/media?parent=115531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/categories?post=115531"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/scalp-sas.com\/en\/wp-json\/wp\/v2\/tags?post=115531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}