{"id":9684,"date":"2023-08-11T13:41:47","date_gmt":"2023-08-11T13:41:47","guid":{"rendered":"https:\/\/scalp-sas.com\/?post_type=video&#038;p=9684"},"modified":"2023-08-11T14:34:25","modified_gmt":"2023-08-11T14:34:25","slug":"traiter-toiture-contre-micro-organismes","status":"publish","type":"video","link":"https:\/\/scalp-sas.com\/de\/video\/behandeln-dach-gegen-mikroorganismen\/","title":{"rendered":"Behandeln Sie Ihr Dach gegen Mikroorganismen - SCALP AM 77"},"content":{"rendered":"<p>Behandeln Sie Ihr Dach gegen Mikroorganismen mit SCALP AM 77, dem bakteriziden, levuroziden und algiziden Konzentrat, das Verunreinigungen angreift. Es ist weit mehr als ein einfacher Reiniger. Denn es beseitigt Algen, Flechten, Mikroorganismen und gr\u00fcnliche Ablagerungen in k\u00fcrzester Zeit unter der Einwirkung von Regen und Wind. Aber das ist noch nicht alles! SCALP AM 77 bietet auch einen langfristigen Schutz, indem es Ihre Oberfl\u00e4chen mehrere Jahre lang vor diesen gr\u00fcnen Ablagerungen sch\u00fctzt.<\/p>\n\n\n\n<p>Wenn Sie mit Oberfl\u00e4chen konfrontiert sind, die von Mikroorganismen befallen sind, ist SCALP AM 77 Ihr Verb\u00fcndeter. Seine konzentrierte, leistungsstarke Formel wirkt tief in die Haut und beseitigt das Wachstum dieser Mikroorganismen innerhalb weniger Wochen. Die Kraft von Regen und Wind wirkt synergetisch mit diesem Konzentrat zusammen, um sichtbare Ergebnisse zu liefern und Ihre Oberfl\u00e4chen sauber zu hinterlassen.<\/p>\n\n\n\n<p>Die Aufgabe von SCALP AM 77 endet jedoch nicht mit der Beseitigung. Es entfaltet auch eine Schutzbarriere, die Ihre Oberfl\u00e4chen vor zuk\u00fcnftigen Angriffen verteidigt. Sie m\u00fcssen sich keine Sorgen mehr um die unerw\u00fcnschte R\u00fcckkehr von Algen, Flechten und Mikroorganismen machen. Ihre Oberfl\u00e4chen bleiben jahrelang sauber und konserviert.<\/p>\n\n\n\n<p>Das Dach gegen Mikroorganismen zu behandeln ist nicht seine einzige Wirkung. Egal, ob Sie bestehende Fl\u00e4chen renovieren oder Neubauten sch\u00fctzen wollen, dieses Konzentrat eignet sich hervorragend f\u00fcr die Anwendung auf Dachziegeln, Schiefer, Schindeln, Steinen, mineralischen Putzen, Ziegeln, Gips, Beton, Putz und vielem mehr.<\/p>\n\n\n\n<p>SCALP AM 77 wird zu Ihrer gef\u00fcrchteten Waffe f\u00fcr m\u00fchelose Sauberkeit und langfristigen Schutz. Mit seiner schnellen Wirkung und lang anhaltenden Verteidigung ist es eine unverzichtbare L\u00f6sung, um Ihre Oberfl\u00e4chen makellos und widerstandsf\u00e4hig gegen unerw\u00fcnschte Eindringlinge zu halten. Vertrauen Sie auf SCALP AM 77, um Ihre Au\u00dfenbereiche einfach und effektiv zu reinigen, zu sch\u00fctzen und zu bewahren.<\/p>","protected":false},"excerpt":{"rendered":"<p>Traiter sa toiture contre les micro-organismes avec SCALP AM 77, le concentr\u00e9 bact\u00e9ricide, levuricide et algicide qui s&rsquo;attaque aux impuret\u00e9s. C&rsquo;est bien plus qu&rsquo;un simple nettoyant. En effet, il \u00e9limine les algues, les lichens, les micro-organismes et les d\u00e9p\u00f4ts verd\u00e2tres en un laps de temps r\u00e9duit, sous l&rsquo;action de la pluie et du vent. Mais [&hellip;]<\/p>","protected":false},"author":2,"featured_media":4615,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categorie_video":[34],"class_list":["post-9684","video","type-video","status-publish","format-standard","has-post-thumbnail","hentry","categorie_video-batiment"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Traiter sa toiture contre les micro-organismes - SCALP AM 77<\/title>\n<meta name=\"description\" content=\"Traiter sa toiture contre les micro-organismes avec SCALP AM 77. Il permet de nettoyer et prot\u00e9ger les toitures des d\u00e9p\u00f4ts verd\u00e2tres.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/scalp-sas.com\/de\/video\/behandeln-dach-gegen-mikroorganismen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Traiter sa toiture contre les micro-organismes - SCALP AM 77\" \/>\n<meta property=\"og:description\" content=\"Traiter sa toiture contre les micro-organismes avec SCALP AM 77. Il permet de nettoyer et prot\u00e9ger les toitures des d\u00e9p\u00f4ts verd\u00e2tres.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/scalp-sas.com\/de\/video\/behandeln-dach-gegen-mikroorganismen\/\" \/>\n<meta property=\"og:site_name\" content=\"SCALP SAS\" \/>\n<meta property=\"article:modified_time\" content=\"2023-08-11T14:34:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/WP_20130426_005-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/\",\"name\":\"Traiter sa toiture contre les micro-organismes - SCALP AM 77\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/WP_20130426_005-scaled.jpg\",\"datePublished\":\"2023-08-11T13:41:47+00:00\",\"dateModified\":\"2023-08-11T14:34:25+00:00\",\"description\":\"Traiter sa toiture contre les micro-organismes avec SCALP AM 77. Il permet de nettoyer et prot\u00e9ger les toitures des d\u00e9p\u00f4ts verd\u00e2tres.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/WP_20130426_005-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/WP_20130426_005-scaled.jpg\",\"width\":2560,\"height\":1440,\"caption\":\"Bact\u00e9ricide levuricide et algicide concentr\u00e9\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/video\\\/traiter-toiture-contre-micro-organismes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"videos\",\"item\":\"https:\\\/\\\/scalp-sas.com\\\/es\\\/videos\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Traiter sa toiture contre les micro-organismes &#8211; SCALP AM 77\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#website\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"name\":\"SCALP SAS\",\"description\":\"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans\",\"publisher\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/scalp-sas.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#organization\",\"name\":\"SCALP SAS\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"contentUrl\":\"https:\\\/\\\/scalp-sas.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/logo-scalp-noir.svg\",\"width\":526.433,\"height\":274.69,\"caption\":\"SCALP SAS\"},\"image\":{\"@id\":\"https:\\\/\\\/scalp-sas.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.linkedin.com\\\/company\\\/scalp-sas\\\/\",\"https:\\\/\\\/www.instagram.com\\\/scalp_sas\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Traiter sa toiture contre les micro-organismes - SCALP AM 77","description":"Traiter sa toiture contre les micro-organismes avec SCALP AM 77. Il permet de nettoyer et prot\u00e9ger les toitures des d\u00e9p\u00f4ts verd\u00e2tres.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/scalp-sas.com\/de\/video\/behandeln-dach-gegen-mikroorganismen\/","og_locale":"de_DE","og_type":"article","og_title":"Traiter sa toiture contre les micro-organismes - SCALP AM 77","og_description":"Traiter sa toiture contre les micro-organismes avec SCALP AM 77. Il permet de nettoyer et prot\u00e9ger les toitures des d\u00e9p\u00f4ts verd\u00e2tres.","og_url":"https:\/\/scalp-sas.com\/de\/video\/behandeln-dach-gegen-mikroorganismen\/","og_site_name":"SCALP SAS","article_modified_time":"2023-08-11T14:34:25+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/WP_20130426_005-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/","url":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/","name":"Traiter sa toiture contre les micro-organismes - SCALP AM 77","isPartOf":{"@id":"https:\/\/scalp-sas.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/#primaryimage"},"image":{"@id":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/#primaryimage"},"thumbnailUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/WP_20130426_005-scaled.jpg","datePublished":"2023-08-11T13:41:47+00:00","dateModified":"2023-08-11T14:34:25+00:00","description":"Traiter sa toiture contre les micro-organismes avec SCALP AM 77. Il permet de nettoyer et prot\u00e9ger les toitures des d\u00e9p\u00f4ts verd\u00e2tres.","breadcrumb":{"@id":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/#primaryimage","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/WP_20130426_005-scaled.jpg","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/11\/WP_20130426_005-scaled.jpg","width":2560,"height":1440,"caption":"Bact\u00e9ricide levuricide et algicide concentr\u00e9"},{"@type":"BreadcrumbList","@id":"https:\/\/scalp-sas.com\/video\/traiter-toiture-contre-micro-organismes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"videos","item":"https:\/\/scalp-sas.com\/es\/videos\/"},{"@type":"ListItem","position":2,"name":"Traiter sa toiture contre les micro-organismes &#8211; SCALP AM 77"}]},{"@type":"WebSite","@id":"https:\/\/scalp-sas.com\/#website","url":"https:\/\/scalp-sas.com\/","name":"SCALP SAS","description":"Sp\u00e9cialiste des solutions de d\u00e9capage, nettoyage, entretien et de protection depuis plus de 70 ans","publisher":{"@id":"https:\/\/scalp-sas.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/scalp-sas.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/scalp-sas.com\/#organization","name":"SCALP SAS","url":"https:\/\/scalp-sas.com\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/","url":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","contentUrl":"https:\/\/scalp-sas.com\/wp-content\/uploads\/2021\/06\/logo-scalp-noir.svg","width":526.433,"height":274.69,"caption":"SCALP SAS"},"image":{"@id":"https:\/\/scalp-sas.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.linkedin.com\/company\/scalp-sas\/","https:\/\/www.instagram.com\/scalp_sas\/"]}]}},"_links":{"self":[{"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/video\/9684","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/video"}],"about":[{"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/types\/video"}],"author":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/comments?post=9684"}],"version-history":[{"count":3,"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/video\/9684\/revisions"}],"predecessor-version":[{"id":9703,"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/video\/9684\/revisions\/9703"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/media\/4615"}],"wp:attachment":[{"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/media?parent=9684"}],"wp:term":[{"taxonomy":"categorie_video","embeddable":true,"href":"https:\/\/scalp-sas.com\/de\/wp-json\/wp\/v2\/categorie_video?post=9684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}